{"id":2369,"date":"2012-10-09T02:20:55","date_gmt":"2012-10-09T04:20:55","guid":{"rendered":"http:\/\/bibliobelas.wordpress.com\/?p=2369"},"modified":"2012-10-09T02:20:55","modified_gmt":"2012-10-09T04:20:55","slug":"semana-de-curtas-internacionais-no-humberto-mauro","status":"publish","type":"post","link":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/2012\/10\/semana-de-curtas-internacionais-no-humberto-mauro\/","title":{"rendered":"Semana de curtas internacionais no Humberto Mauro"},"content":{"rendered":"<p style=\"text-align:right;\">DANIEL TOLEDO<\/p>\n<p style=\"text-align:justify;\">\u00a0De ontem, 08\/11, a sexta-feira, o Cine Humberto Mauro recebe a programa\u00e7\u00e3o do Mumia, mostra de cinema de anima\u00e7\u00e3o que teve in\u00edcio na semana passada. Finalizada a mostra de curtas nacionais, realizada at\u00e9 ontem, \u00e9 chegada a hora do p\u00fablico belo-horizontino conhecer o amplo conjunto de produ\u00e7\u00f5es estrangeiras inscritas no evento, que tem como um de seus principais diferenciais a aus\u00eancia de curadoria.<\/p>\n<p style=\"text-align:justify;\"><a href=\"https:\/\/bibliobelas.eba.ufmg.br\/wp-content\/uploads\/2012\/10\/foto_07102012195751.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-2370\" title=\"foto_07102012195751\" src=\"https:\/\/bibliobelas.eba.ufmg.br\/wp-content\/uploads\/2012\/10\/foto_07102012195751.jpg?w=300\" alt=\"\" width=\"300\" height=\"222\" srcset=\"https:\/\/bibliobelas.eba.ufmg.br\/wp-content\/uploads\/2012\/10\/foto_07102012195751.jpg 600w, https:\/\/bibliobelas.eba.ufmg.br\/wp-content\/uploads\/2012\/10\/foto_07102012195751-300x222.jpg 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Dentro desse grupo, conta o organizador S\u00e1vio Leite, est\u00e3o obras marcadas pela experimenta\u00e7\u00e3o de linguagens e realizadas a partir de v\u00e1rias t\u00e9cnicas, muitas vezes capazes de surpreender o espectador mais acostumado a assistir este ou aquele tipo de anima\u00e7\u00e3o.<\/p>\n<p style=\"text-align:justify;\">&#8220;Para falar a verdade, \u00e9 bem dif\u00edcil diferenciar um curta de anima\u00e7\u00e3o dos que s\u00e3o feitos em outras linguagens. Temos, hoje em dia, in\u00fameros exemplos de trabalhos que chamam aten\u00e7\u00e3o justamente pelo hibridismo de linguagens, inaugurado por filmes como \u0091American Pop\u0092, de Ralph Bakshi, \u0091Valsa com Bashir\u0092 ou at\u00e9 mesmo o hollywoodiano \u0091Waking Life\u0092&#8221;, exemplifica o coordenador, em refer\u00eancia a alguns longa-metragens que marcaram \u00e9poca justamente pela experimenta\u00e7\u00e3o de linguagens.<\/p>\n<p style=\"text-align:justify;\">Com sess\u00f5es geralmente realizadas entre as 17h e as 21h, o festival exibe dezenas de filmes de hoje a quinta-feira, trazendo representantes de mais de 30 pa\u00edses. Apontado por Leite como um dos destaques do evento, o curta franc\u00eas &#8220;Tempestade no Quarto&#8221; ser\u00e1 exibido hoje, no programa das 17h.<\/p>\n<p>Na sexta-feira, Dia das Crian\u00e7as, o Cine Humberto Mauro recebe dois programas especialmente elaborados para os p\u00fablico infantil, com exibi\u00e7\u00e3o de curtas \u00e0s 17h e \u00e0s 18h30, e juvenil, \u00e0s 20h e 21h.<\/p>\n<p style=\"text-align:justify;\">Agenda<a href=\"mailto:PB@agenda,1,3,0,3,4,-1,0&gt;&lt;PS@10,0&gt;&lt;CW-15&gt;&lt;COC030&gt;Agenda&lt;\/CO\"><br \/>\n<\/a><br \/>\nO qu\u00ea. Mumia &#8211; Mostra Udigrudi Internacional de Anima\u00e7\u00e3o (mostra internacional)<br \/>\nQuando. De hoje a sexta-feira<br \/>\nOnde. Cine Humberto Mauro, no Pal\u00e1cio das Artes (av. Afonso Pena, 1.537, centro)<br \/>\nQuanto. Entrada gratuita<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DANIEL TOLEDO \u00a0De ontem, 08\/11, a sexta-feira, o Cine Humberto Mauro recebe a programa\u00e7\u00e3o do Mumia, mostra de cinema de anima\u00e7\u00e3o que teve in\u00edcio na semana passada. Finalizada a mostra de curtas nacionais, realizada at\u00e9 ontem, \u00e9 chegada a hora do p\u00fablico belo-horizontino conhecer o amplo conjunto de produ\u00e7\u00f5es estrangeiras inscritas no evento, que tem &hellip; <a href=\"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/2012\/10\/semana-de-curtas-internacionais-no-humberto-mauro\/\" class=\"more-link\">Continue lendo <span class=\"screen-reader-text\">Semana de curtas internacionais no Humberto Mauro<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[44],"class_list":["post-2369","post","type-post","status-publish","format-standard","hentry","category-postagens","tag-cinema-de-animacao"],"_links":{"self":[{"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts\/2369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/comments?post=2369"}],"version-history":[{"count":0,"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/posts\/2369\/revisions"}],"wp:attachment":[{"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/media?parent=2369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/categories?post=2369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bibliobelas.eba.ufmg.br\/index.php\/wp-json\/wp\/v2\/tags?post=2369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}